{"id":61,"count":2,"description":"","link":"https:\/\/enjoyibizacharter.com\/en\/categoria\/tips\/","name":"Tips","slug":"tips","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.6 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Tips archivos - Enjoy Ibiza Charter<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tips archivos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/enjoyibizacharter.com\/en\/categoria\/tips\/\" \/>\n<meta property=\"og:site_name\" content=\"Enjoy Ibiza Charter\" \/>\n<meta property=\"og:image\" content=\"https:\/\/enjoyibizacharter.com\/wp-content\/uploads\/2026\/02\/icono-enjoy-ibiza-charter.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/enjoyibizacharter.com\\\/en\\\/categoria\\\/tips\\\/\",\"url\":\"https:\\\/\\\/enjoyibizacharter.com\\\/en\\\/categoria\\\/tips\\\/\",\"name\":\"Tips archivos - Enjoy Ibiza Charter\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/enjoyibizacharter.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/enjoyibizacharter.com\\\/en\\\/categoria\\\/tips\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/enjoyibizacharter.com\\\/en\\\/categoria\\\/tips\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/enjoyibizacharter.com\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tips\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/enjoyibizacharter.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/enjoyibizacharter.com\\\/en\\\/\",\"name\":\"Enjoy Ibiza Charter\",\"description\":\"Charter y Servicios N\u00e1uticos en Ibiza\",\"publisher\":{\"@id\":\"https:\\\/\\\/enjoyibizacharter.com\\\/en\\\/#organization\"},\"alternateName\":\"Enjoy Ibiza Charter\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/enjoyibizacharter.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/enjoyibizacharter.com\\\/en\\\/#organization\",\"name\":\"Enjoy Ibiza Charter\",\"alternateName\":\"Enjoy Ibiza Charter\",\"url\":\"https:\\\/\\\/enjoyibizacharter.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/enjoyibizacharter.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/enjoyibizacharter.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/icono-enjoy-ibiza-charter.webp\",\"contentUrl\":\"https:\\\/\\\/enjoyibizacharter.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/icono-enjoy-ibiza-charter.webp\",\"width\":512,\"height\":512,\"caption\":\"Enjoy Ibiza Charter\"},\"image\":{\"@id\":\"https:\\\/\\\/enjoyibizacharter.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/enjoyibizacharter\",\"https:\\\/\\\/www.instagram.com\\\/enjoyibizacharter\"],\"description\":\"Empresa especializada en charter n\u00e1utico con gesti\u00f3n directa de flota en Ibiza y Formentera. M\u00e1s de 15 a\u00f1os de experiencia y equipo local.\",\"email\":\"info@enjoyibizacharter.com\",\"telephone\":\"(+34) 640 559 890\",\"legalName\":\"Enjoy Ibiza Charter\",\"vatID\":\"X3630038V\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tips archivos - Enjoy Ibiza Charter","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Tips archivos","og_url":"https:\/\/enjoyibizacharter.com\/en\/categoria\/tips\/","og_site_name":"Enjoy Ibiza Charter","og_image":[{"width":512,"height":512,"url":"https:\/\/enjoyibizacharter.com\/wp-content\/uploads\/2026\/02\/icono-enjoy-ibiza-charter.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/enjoyibizacharter.com\/en\/categoria\/tips\/","url":"https:\/\/enjoyibizacharter.com\/en\/categoria\/tips\/","name":"Tips archivos - Enjoy Ibiza Charter","isPartOf":{"@id":"https:\/\/enjoyibizacharter.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/enjoyibizacharter.com\/en\/categoria\/tips\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/enjoyibizacharter.com\/en\/categoria\/tips\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/enjoyibizacharter.com\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Tips"}]},{"@type":"WebSite","@id":"https:\/\/enjoyibizacharter.com\/en\/#website","url":"https:\/\/enjoyibizacharter.com\/en\/","name":"Enjoy Ibiza Charter","description":"Charter y Servicios N\u00e1uticos en Ibiza","publisher":{"@id":"https:\/\/enjoyibizacharter.com\/en\/#organization"},"alternateName":"Enjoy Ibiza Charter","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/enjoyibizacharter.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/enjoyibizacharter.com\/en\/#organization","name":"Enjoy Ibiza Charter","alternateName":"Enjoy Ibiza Charter","url":"https:\/\/enjoyibizacharter.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/enjoyibizacharter.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/enjoyibizacharter.com\/wp-content\/uploads\/2026\/02\/icono-enjoy-ibiza-charter.webp","contentUrl":"https:\/\/enjoyibizacharter.com\/wp-content\/uploads\/2026\/02\/icono-enjoy-ibiza-charter.webp","width":512,"height":512,"caption":"Enjoy Ibiza Charter"},"image":{"@id":"https:\/\/enjoyibizacharter.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/enjoyibizacharter","https:\/\/www.instagram.com\/enjoyibizacharter"],"description":"Empresa especializada en charter n\u00e1utico con gesti\u00f3n directa de flota en Ibiza y Formentera. M\u00e1s de 15 a\u00f1os de experiencia y equipo local.","email":"info@enjoyibizacharter.com","telephone":"(+34) 640 559 890","legalName":"Enjoy Ibiza Charter","vatID":"X3630038V"}]}},"_links":{"self":[{"href":"https:\/\/enjoyibizacharter.com\/en\/wp-json\/wp\/v2\/categories\/61","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/enjoyibizacharter.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/enjoyibizacharter.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/enjoyibizacharter.com\/en\/wp-json\/wp\/v2\/posts?categories=61"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}